{"id":939,"date":"2021-12-01T09:00:00","date_gmt":"2021-12-01T14:00:00","guid":{"rendered":"https:\/\/blog.source.immo\/?p=287"},"modified":"2023-01-05T19:11:20","modified_gmt":"2023-01-06T00:11:20","slug":"vente-de-succession-ce-qu-il-faut-savoir","status":"publish","type":"post","link":"https:\/\/equipecajolais.com\/en\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/","title":{"rendered":"Vente de succession : ce qu\u2019il faut savoir"},"content":{"rendered":"\n<p>Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Preuve du droit \u00e0 la succession<\/strong><\/h2>\n\n\n\n<p>Pour qu\u2019une personne puisse recevoir par succession, il faut qu\u2019elle cumule les qualit\u00e9s \u00e9nonc\u00e9es au Code civil du Qu\u00e9bec, c\u2019est -\u00e0-dire exister juridiquement et ne pas \u00eatre indigne<strong>.<\/strong><\/p>\n\n\n\n<p>Pour en savoir plus&nbsp;:&nbsp;<a href=\"https:\/\/educaloi.qc.ca\/capsules\/les-principales-etapes-dune-liquidation-de-succession\"><strong>https:\/\/educaloi.qc.ca\/capsules\/les-principales-etapes-dune-liquidation-de-succession<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quand peut-on vendre la propri\u00e9t\u00e9?<\/strong><\/h2>\n\n\n\n<p>Une fois que tous les h\u00e9ritiers se mettent d\u2019accord pour proc\u00e9der \u00e0 la vente de&nbsp;<a href=\"https:\/\/www.centris.ca\/fr\/blogue\/immobilier\/en-absence-de-testament-a-qui-revient-l-heritage?uc=0\">succession<\/a>, la premi\u00e8re \u00e9tape consiste \u00e0 obtenir une \u00ab\u2009d\u00e9claration de transmission relative \u00e0 un immeuble\u2009\u00bb. Ce document est pr\u00e9par\u00e9 par un notaire. Il s\u2019agit d\u2019un acte notari\u00e9 inscrit au registre foncier du Qu\u00e9bec qui officialise le transfert de la propri\u00e9t\u00e9 aux h\u00e9ritiers.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Que doit-on fournir pour obtenir une d\u00e9claration de transmission?<\/strong><\/h2>\n\n\n\n<p>Afin d\u2019enregistrer le transfert de propri\u00e9t\u00e9, le notaire doit rassembler divers documents, dont le certificat de d\u00e9c\u00e8s, le testament, l\u2019acte de vente qui confirme que le d\u00e9funt poss\u00e9dait la propri\u00e9t\u00e9, le certificat de localisation et d\u2019autres documents, en fonction de la situation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qui d\u00e9cide de vendre ou non la maison?<\/strong><\/h2>\n\n\n\n<p>Si la maison est l\u00e9gu\u00e9e \u00e0 plusieurs personnes, celles-ci doivent s\u2019entendre \u00e0 l\u2019unanimit\u00e9 sur le sort r\u00e9serv\u00e9 \u00e0 la maison. Tous doivent donc \u00eatre d\u2019accord pour vendre la maison. Si quelqu\u2019un veut la garder, les h\u00e9ritiers devront s\u2019entendre sur une solution commune.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Est-il pr\u00e9f\u00e9rable d\u2019effectuer des travaux avant la mise en vente?<\/strong><\/h2>\n\n\n\n<p>Il n\u2019est pas recommand\u00e9 d\u2019effectuer d\u2019importants travaux, sauf s\u2019ils sont essentiels. En fait, il faut s\u2019assurer de maintenir la propri\u00e9t\u00e9 en bon \u00e9tat et pr\u00e9sentable, comme on le ferait pour toute autre vente de maison. Cela veut dire qu\u2019il faut faire le m\u00e9nage et s\u2019occuper de l\u2019am\u00e9nagement ext\u00e9rieur en attendant la vente de la maison. Bien entendu, si des r\u00e9parations sont n\u00e9cessaires, il faut s\u2019en occuper.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Faut-il vider la maison avant la vente?<\/strong><\/h2>\n\n\n\n<p>Quand on proc\u00e8de \u00e0 une vente de succession, il peut \u00eatre tentant de vider la maison au plus vite, parce qu\u2019on veut clore son deuil. Attention, il ne faut pas agir avec trop de pr\u00e9cipitations\u00a0: une maison vide n\u2019est pas toujours aussi \u00ab\u2009vendeuse\u2009\u00bb. De plus, certains acheteurs pourraient vouloir acqu\u00e9rir des meubles laiss\u00e9s par le d\u00e9funt. Il faut plut\u00f4t faire comme le sugg\u00e8rent les\u00a0<a href=\"https:\/\/apciq.ca\/faire-equipe-avec-un-courtier\/\">courtiers immobiliers<\/a>\u00a0lors de la vente de n\u2019importe quelle maison\u00a0: cr\u00e9ez un d\u00e9cor agr\u00e9able,\u00a0<a href=\"https:\/\/www.centris.ca\/fr\/blogue\/astuces-et-deco\/depersonnaliser-votre-maison-pour-la-vendre?uc=3\">d\u00e9personnalis\u00e9<\/a>. Retirer les photos souvenirs encadr\u00e9es aux murs pour les remplacer par des photos d\u00e9coratives et inspirantes est donc important. L\u2019objectif de ce \u00ab\u2009<a href=\"https:\/\/www.centris.ca\/fr\/blogue\/astuces-et-deco\/5-principes-a-retenir-pour-un-home-staging-reussi?uc=0\">staging<\/a>\u2009\u00bb\u00a0: offrir aux acheteurs potentiels un environnement dans lequel ils pourront s\u2019imaginer vivre.\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Que faire si l\u2019on veut vendre rapidement?<\/strong><\/h2>\n\n\n\n<p>En travaillant avec un courtier immobilier, les h\u00e9ritiers r\u00e9duisent grandement les sources de conflits potentiels. Le courtier est le professionnel le mieux plac\u00e9 pour effectuer les visites, recevoir les offres et diriger la n\u00e9gociation. Il sait aussi quels documents et obligations doivent \u00eatre remplis.<\/p>\n\n\n\n<p>Une vente de succession rapide est g\u00e9n\u00e9ralement souhait\u00e9e par les h\u00e9ritiers. Une vente de succession est toujours effectu\u00e9e sans garantie l\u00e9gale (ou caution judiciaire). \u00c7a permet de d\u00e9gager les h\u00e9ritiers d\u2019ennuis \u00e9ventuels au sujet d\u2019une propri\u00e9t\u00e9 qu\u2019ils connaissent peu ou pas. \u00c9videmment, il faut parfois ajuster le prix en cons\u00e9quence, mais si quelqu\u2019un accepte cette condition, la vente peut se faire rapidement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vous souhaitez vendre? Faites appel \u00e0 un courtier!<\/strong><\/h2>\n\n\n\n<p>En tout temps, quand vient le temps de vendre sa propri\u00e9t\u00e9 faites appel \u00e0 un professionnel form\u00e9, le courtier immobilier sera votre alli\u00e9! Une vente de succession est complexe et les risques d\u2019emb\u00fbches sont encore plus nombreux que lors d\u2019une vente \u00ab&nbsp;normale&nbsp;\u00bb. Ne prenez pas de risques, trouvez votre courtier sur&nbsp;<a href=\"https:\/\/www.centris.ca\/fr\/courtiers-immobiliers\">centris.ca&nbsp;<\/a>&nbsp;<\/p>\n\n\n\n<p>Pour plus d\u2019informations\u00a0:\u00a0<a href=\"https:\/\/www.justice.gouv.qc.ca\/votre-argent-et-vos-biens\/successions\/\">https:\/\/www.justice.gouv.qc.ca\/votre-argent-et-vos-biens\/successions\/<\/a><\/p>\n\n\n\n<p><em>Source : blogue de Centris :<a href=\"https:\/\/www.centris.ca\/fr\/blogue\/immobilier\/vente-de-succession-ce-qu-il-faut-savoir?uc=0\" target=\"_blank\" rel=\"noreferrer noopener\"> https:\/\/www.centris.ca\/fr\/blogue\/immobilier\/vente-de-succession-ce-qu-il-faut-savoir?uc=0<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.<\/p>\n","protected":false},"author":1,"featured_media":1400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,13],"tags":[],"class_list":["post-939","post","type-post","status-publish","format-standard","hentry","category-aliquando","category-finance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vente de succession : ce qu\u2019il faut savoir - \u00c9quipe Cajolais - Remax Qu\u00e9bec<\/title>\n<meta name=\"description\" content=\"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vente de succession : ce qu\u2019il faut savoir\" \/>\n<meta property=\"og:description\" content=\"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Cajolais - Remax Qu\u00e9bec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EquipeCajolais\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-06T00:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Vente de succession : ce qu\u2019il faut savoir\" \/>\n<meta name=\"twitter:description\" content=\"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Vente de succession : ce qu\u2019il faut savoir\",\"datePublished\":\"2021-12-01T14:00:00+00:00\",\"dateModified\":\"2023-01-06T00:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\"},\"wordCount\":739,\"image\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg\",\"articleSection\":[\"Aliquando\",\"Finance\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\",\"url\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\",\"name\":\"Vente de succession : ce qu\u2019il faut savoir - \u00c9quipe Cajolais - Remax Qu\u00e9bec\",\"isPartOf\":{\"@id\":\"https:\/\/equipecajolais.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg\",\"datePublished\":\"2021-12-01T14:00:00+00:00\",\"dateModified\":\"2023-01-06T00:11:20+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.\",\"breadcrumb\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage\",\"url\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg\",\"contentUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg\",\"width\":940,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/equipecajolais.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vente de succession : ce qu\u2019il faut savoir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/equipecajolais.com\/#website\",\"url\":\"https:\/\/equipecajolais.com\/\",\"name\":\"\u00c9quipe Cajolais - Remax Qu\u00e9bec\",\"description\":\"Real Estate brokers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/equipecajolais.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/equipecajolais.com\/en\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vente de succession : ce qu\u2019il faut savoir - \u00c9quipe Cajolais - Remax Qu\u00e9bec","description":"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/","og_locale":"en_US","og_type":"article","og_title":"Vente de succession : ce qu\u2019il faut savoir","og_description":"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.","og_url":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/","og_site_name":"\u00c9quipe Cajolais - Remax Qu\u00e9bec","article_publisher":"https:\/\/www.facebook.com\/EquipeCajolais","article_published_time":"2021-12-01T14:00:00+00:00","article_modified_time":"2023-01-06T00:11:20+00:00","og_image":[{"url":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Vente de succession : ce qu\u2019il faut savoir","twitter_description":"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.","twitter_image":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg","twitter_misc":{"Written by":"","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#article","isPartOf":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/"},"author":{"name":"","@id":""},"headline":"Vente de succession : ce qu\u2019il faut savoir","datePublished":"2021-12-01T14:00:00+00:00","dateModified":"2023-01-06T00:11:20+00:00","mainEntityOfPage":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/"},"wordCount":739,"image":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg","articleSection":["Aliquando","Finance"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/","url":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/","name":"Vente de succession : ce qu\u2019il faut savoir - \u00c9quipe Cajolais - Remax Qu\u00e9bec","isPartOf":{"@id":"https:\/\/equipecajolais.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage"},"image":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg","datePublished":"2021-12-01T14:00:00+00:00","dateModified":"2023-01-06T00:11:20+00:00","author":{"@id":""},"description":"Vous venez d\u2019h\u00e9riter d\u2019une maison? Savez-vous ce que cela implique? De nombreuses questions viennent \u00e0 vous et c\u2019est normal, voici quelques informations pour mieux comprendre les diff\u00e9rents enjeux.","breadcrumb":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#primaryimage","url":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg","contentUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/12\/Vente-de-succession-ce-quil-faut-savoir.jpg","width":940,"height":625},{"@type":"BreadcrumbList","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/vente-de-succession-ce-qu-il-faut-savoir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/equipecajolais.com\/"},{"@type":"ListItem","position":2,"name":"Vente de succession : ce qu\u2019il faut savoir"}]},{"@type":"WebSite","@id":"https:\/\/equipecajolais.com\/#website","url":"https:\/\/equipecajolais.com\/","name":"\u00c9quipe Cajolais - Remax Qu\u00e9bec","description":"Real Estate brokers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equipecajolais.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/equipecajolais.com\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts\/939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/comments?post=939"}],"version-history":[{"count":1,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts\/939\/revisions"}],"predecessor-version":[{"id":1085,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts\/939\/revisions\/1085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/media\/1400"}],"wp:attachment":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/media?parent=939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/categories?post=939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/tags?post=939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}