{"id":977,"date":"2021-07-19T09:00:00","date_gmt":"2021-07-19T13:00:00","guid":{"rendered":"https:\/\/blog.source.immo\/?p=155"},"modified":"2023-01-05T19:11:22","modified_gmt":"2023-01-06T00:11:22","slug":"barometre-marche-residentiel-2e-trimestre-2021","status":"publish","type":"post","link":"https:\/\/equipecajolais.com\/en\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/","title":{"rendered":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021"},"content":{"rendered":"\n<p>Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion&nbsp;et&nbsp;affiche&nbsp;des records de vente et de prix.\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ventes<\/strong><\/h2>\n\n\n\n<p>31 899 ventes r\u00e9sidentielles ont \u00e9t\u00e9 conclues au 2<sup>e<\/sup>&nbsp;trimestre 2021 ce qui repr\u00e9sente une hausse de 45 % par rapport \u00e0 la m\u00eame p\u00e9riode l\u2019an dernier.<\/p>\n\n\n\n<p>\u00ab\u2009Un an apr\u00e8s les mesures de confinement qui avaient fait chuter l\u2019activit\u00e9 transactionnelle, force est de constater que le march\u00e9 a fait plus que rebondir\u202f: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.&nbsp;<a>Si<\/a><a href=\"https:\/\/www.centris.ca\/#_msocom_1\">[MB1]<\/a>&nbsp;&nbsp;au deuxi\u00e8me\u202ftrimestre de 2021, on enregistrait encore de nouveaux records on remarquait aussi, en contrepartie, une d\u00e9c\u00e9l\u00e9ration du rythme de croissance de l\u2019activit\u00e9 \u00bb, commente Charles\u202fBrant, directeur du Service de l\u2019analyse du march\u00e9 de l\u2019APCIQ.&nbsp;<\/p>\n\n\n\n<p>Si l\u2019on regarde par cat\u00e9gorie de propri\u00e9t\u00e9s, 19 842 maisons unifamiliales ont \u00e9t\u00e9 vendues au 2<sup>e<\/sup>&nbsp;trimestre, soit 28 % de plus qu\u2019\u00e0 la m\u00eame p\u00e9riode l\u2019ann\u00e9e derni\u00e8re. Les ventes de copropri\u00e9t\u00e9s ont bondi de 76 % et celles des plex de 119 % avec 3 505 transactions conclues. Les ventes de cette cat\u00e9gorie avaient recul\u00e9 de 33\u202f%, passant de 2\u2009391\u202fventes en 2019 \u00e0 1\u2009604 au deuxi\u00e8me trimestre de 2020.<\/p>\n\n\n\n<p>Enfin, du c\u00f4t\u00e9 des 6 RMR, la RMR de Montr\u00e9al a connu une hausse&nbsp;tr\u00e8s&nbsp;soutenue&nbsp;des ventes (60\u202f%),&nbsp;hausse&nbsp;d\u2019abord et avant tout li\u00e9e aux&nbsp;incidences&nbsp;de la crise sanitaire sur la m\u00eame p\u00e9riode l\u2019an dernier. La RMR de Montr\u00e9al avait&nbsp;enregistr\u00e9&nbsp;une chute de 36\u202f% de ses ventes r\u00e9sidentielles&nbsp;comparativement&nbsp;\u00e0 une moyenne de -19\u202f% pour les&nbsp;cinq autres&nbsp;r\u00e9gions m\u00e9tropolitaines du&nbsp;Qu\u00e9bec.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.centris.ca\/public\/cms\/qc\/consumersite\/0d27c78c073c46cca18f0d8d848c38b9\/visuel%20bar%20bloguefr.jpg\" alt=\"\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Prix<\/strong><\/h2>\n\n\n\n<p>\u00c0 l\u2019\u00e9chelle provinciale,&nbsp;le prix m\u00e9dian des unifamiliales s\u2019est \u00e9tabli \u00e0 373 000&nbsp;$ au 2<sup>e<\/sup>&nbsp;trimestre, soit une hausse de 35 % par rapport \u00e0 2020. Les prix m\u00e9dians sont aussi en croissance pour la copropri\u00e9t\u00e9 (335&nbsp;000 $, +31 %) et les petits plex (470 000 $, +23 %).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Inscriptions en vigueur<\/strong><\/h2>\n\n\n\n<p>Au 2<sup>e<\/sup>&nbsp;trimestre 2021, l\u2019inventaire a chut\u00e9 de 36 % par rapport \u00e0 la m\u00eame p\u00e9riode en 2020.<\/p>\n\n\n\n<p><strong>Conditions du march\u00e9 et d\u00e9lais de vente<\/strong><\/p>\n\n\n\n<p>La baisse&nbsp;de&nbsp;propri\u00e9t\u00e9s \u00e0 vendre&nbsp;s\u2019est poursuivie&nbsp;\u00e0 l\u2019\u00e9chelle de la province&nbsp;et a&nbsp;atteint un record\u202f:&nbsp;au deuxi\u00e8me trimestre&nbsp;de&nbsp;2021,&nbsp;il y avait moins de&nbsp;trois\u202fmois d\u2019inventaire de propri\u00e9t\u00e9s&nbsp;sur le march\u00e9, du jamais vu depuis que le syst\u00e8me&nbsp;Centris&nbsp;compile les donn\u00e9es de march\u00e9.&nbsp;Le ralentissement de l\u2019activit\u00e9 observ\u00e9 en juin pourrait toutefois&nbsp;tendre \u00e0 renverser la&nbsp;tendance au troisi\u00e8me trimestre.&nbsp;<\/p>\n\n\n\n<p>Pour des statistiques plus d\u00e9taill\u00e9es sur chacune des r\u00e9gions du Qu\u00e9bec, consultez le\u00a0<a href=\"https:\/\/com.apciq.ca\/sam\/pdf\/bar\/2019\/201904-bar-province.pdf\"><strong>Barom\u00e8tre APCIQ<\/strong><\/a><strong>\u00a0et visitez\u00a0<a href=\"https:\/\/apciq.ca\/marche-immobilier\/\">https:\/\/apciq.ca\/marche-immobilier<strong>\/<\/strong><\/a><\/strong><\/p>\n\n\n\n<p><em>Source : blogue de Centris : <a href=\"https:\/\/www.centris.ca\/fr\/blogue\/immobilier\/barometre-du-marche-residentiel-du-2e-trimestre-de-2021?uc=0\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.centris.ca\/fr\/blogue\/immobilier\/barometre-du-marche-residentiel-du-2e-trimestre-de-2021?uc=0<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.<\/p>\n","protected":false},"author":1,"featured_media":1423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,13,15,24],"tags":[],"class_list":["post-977","post","type-post","status-publish","format-standard","hentry","category-aliquando","category-finance","category-investissement","category-residentiel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021 - \u00c9quipe Cajolais - Remax Qu\u00e9bec<\/title>\n<meta name=\"description\" content=\"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021\" \/>\n<meta property=\"og:description\" content=\"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Cajolais - Remax Qu\u00e9bec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EquipeCajolais\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-19T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-06T00:11:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021\" \/>\n<meta name=\"twitter:description\" content=\"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021\",\"datePublished\":\"2021-07-19T13:00:00+00:00\",\"dateModified\":\"2023-01-06T00:11:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\"},\"wordCount\":539,\"image\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg\",\"articleSection\":[\"Aliquando\",\"Finance\",\"Investissement\",\"R\u00e9sidentiel\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\",\"url\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\",\"name\":\"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021 - \u00c9quipe Cajolais - Remax Qu\u00e9bec\",\"isPartOf\":{\"@id\":\"https:\/\/equipecajolais.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg\",\"datePublished\":\"2021-07-19T13:00:00+00:00\",\"dateModified\":\"2023-01-06T00:11:22+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.\",\"breadcrumb\":{\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage\",\"url\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg\",\"contentUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg\",\"width\":1200,\"height\":805},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/equipecajolais.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/equipecajolais.com\/#website\",\"url\":\"https:\/\/equipecajolais.com\/\",\"name\":\"\u00c9quipe Cajolais - Remax Qu\u00e9bec\",\"description\":\"Real Estate brokers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/equipecajolais.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/equipecajolais.com\/en\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021 - \u00c9quipe Cajolais - Remax Qu\u00e9bec","description":"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/","og_locale":"en_US","og_type":"article","og_title":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021","og_description":"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.","og_url":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/","og_site_name":"\u00c9quipe Cajolais - Remax Qu\u00e9bec","article_publisher":"https:\/\/www.facebook.com\/EquipeCajolais","article_published_time":"2021-07-19T13:00:00+00:00","article_modified_time":"2023-01-06T00:11:22+00:00","og_image":[{"url":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021","twitter_description":"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.","twitter_image":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg","twitter_misc":{"Written by":"","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#article","isPartOf":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/"},"author":{"name":"","@id":""},"headline":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021","datePublished":"2021-07-19T13:00:00+00:00","dateModified":"2023-01-06T00:11:22+00:00","mainEntityOfPage":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/"},"wordCount":539,"image":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg","articleSection":["Aliquando","Finance","Investissement","R\u00e9sidentiel"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/","url":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/","name":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021 - \u00c9quipe Cajolais - Remax Qu\u00e9bec","isPartOf":{"@id":"https:\/\/equipecajolais.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage"},"image":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg","datePublished":"2021-07-19T13:00:00+00:00","dateModified":"2023-01-06T00:11:22+00:00","author":{"@id":""},"description":"Selon l\u2019Association professionnelle des courtiers immobiliers du Qu\u00e9bec (APCIQ), \u00ab Le march\u00e9 immobilier a fait plus que rebondir: il a connu une acc\u00e9l\u00e9ration ph\u00e9nom\u00e9nale de son expansion et affiche des records de vente et de prix.\u00bb.","breadcrumb":{"@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#primaryimage","url":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg","contentUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/07\/province_quebec_fr.jpg","width":1200,"height":805},{"@type":"BreadcrumbList","@id":"http:\/\/78940.b.aliquando.immo\/aliquando\/barometre-marche-residentiel-2e-trimestre-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/equipecajolais.com\/"},{"@type":"ListItem","position":2,"name":"Barom\u00e8tre du march\u00e9 r\u00e9sidentiel du 2e trimestre de 2021"}]},{"@type":"WebSite","@id":"https:\/\/equipecajolais.com\/#website","url":"https:\/\/equipecajolais.com\/","name":"\u00c9quipe Cajolais - Remax Qu\u00e9bec","description":"Real Estate brokers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equipecajolais.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/equipecajolais.com\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts\/977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/comments?post=977"}],"version-history":[{"count":1,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts\/977\/revisions"}],"predecessor-version":[{"id":1123,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/posts\/977\/revisions\/1123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/media\/1423"}],"wp:attachment":[{"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/media?parent=977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/categories?post=977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipecajolais.com\/en\/wp-json\/wp\/v2\/tags?post=977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}